
{"id":6140,"date":"2017-05-23T02:36:09","date_gmt":"2017-05-23T02:36:09","guid":{"rendered":"http:\/\/vainoithatkhachsan.com\/trang-mau\/"},"modified":"2017-06-22T11:38:33","modified_gmt":"2017-06-22T04:38:33","slug":"trang-mau","status":"publish","type":"page","link":"https:\/\/vainoithatkhachsan.com\/en\/","title":{"rendered":"Home"},"content":{"rendered":"\t<section class=\"section\" id=\"section_1173639085\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-collapse row-full-width\"  id=\"row-276534525\">\n\n\t<div id=\"col-848631318\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"slider-wrapper relative\" id=\"slider-541683943\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1949365504\">\n\t\t\t\t\t\t<div data-animate=\"fadeInUp\">\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1349\" height=\"500\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/1450478311510054432cd7e1e157e8ad.png\" class=\"attachment-original size-original\" alt=\"1450478311510054432cd7e1e157e8ad\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/1450478311510054432cd7e1e157e8ad.png 1349w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/1450478311510054432cd7e1e157e8ad-600x222.png 600w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/1450478311510054432cd7e1e157e8ad-800x297.png 800w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/1450478311510054432cd7e1e157e8ad-768x285.png 768w\" sizes=\"(max-width: 1349px) 100vw, 1349px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t\t\t\n<style>\n#image_1949365504 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_542346876\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"378\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/14504783466cd1c6c997dc22b77e8209.png\" class=\"attachment-large size-large\" alt=\"14504783466cd1c6c997dc22b77e8209\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/14504783466cd1c6c997dc22b77e8209.png 1349w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/14504783466cd1c6c997dc22b77e8209-600x222.png 600w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/14504783466cd1c6c997dc22b77e8209-800x297.png 800w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/14504783466cd1c6c997dc22b77e8209-768x285.png 768w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_542346876 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1731918752\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"378\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/1450477508fb2517c34abfecac041542.png\" class=\"attachment-large size-large\" alt=\"1450477508fb2517c34abfecac041542\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/1450477508fb2517c34abfecac041542.png 1349w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/1450477508fb2517c34abfecac041542-600x222.png 600w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/1450477508fb2517c34abfecac041542-800x297.png 800w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/1450477508fb2517c34abfecac041542-768x285.png 768w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1731918752 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_518121499\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"378\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/1450477531428f849333ab8a418f9354.png\" class=\"attachment-large size-large\" alt=\"1450477531428f849333ab8a418f9354\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/1450477531428f849333ab8a418f9354.png 1349w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/1450477531428f849333ab8a418f9354-600x222.png 600w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/1450477531428f849333ab8a418f9354-800x297.png 800w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/1450477531428f849333ab8a418f9354-768x285.png 768w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_518121499 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1556948383\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"378\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/145047828381aca8bf50f78473e26958.png\" class=\"attachment-large size-large\" alt=\"145047828381aca8bf50f78473e26958\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/145047828381aca8bf50f78473e26958.png 1349w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/145047828381aca8bf50f78473e26958-600x222.png 600w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/145047828381aca8bf50f78473e26958-800x297.png 800w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/145047828381aca8bf50f78473e26958-768x285.png 768w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1556948383 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n     \t<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1173639085 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(241, 241, 241);\n}\n#section_1173639085 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1173639085 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section section-categories hide-for-medium\" id=\"section_2020118787\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-collapse align-middle\"  id=\"row-302646682\">\n\n\t<div id=\"col-2051646784\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"http:\/\/vainoithatkhachsan.com\/danh-muc\/chan-ga-goi-khach-san\/chan-ga-goi\/\" target=\"_self\" class=\"button primary is-link\"  >\n    <span>Blanket<\/span>\n  <\/a>\n\n<a href=\"http:\/\/vainoithatkhachsan.com\/danh-muc\/chan-ga-goi-khach-san\/ruot-goi\/\" target=\"_self\" class=\"button primary is-link\"  >\n    <span>PILLOW<\/span>\n  <\/a>\n\n<a href=\"http:\/\/vainoithatkhachsan.com\/danh-muc\/nem\/\" target=\"_self\" class=\"button primary is-link\"  >\n    <span>MATTRESS<\/span>\n  <\/a>\n\n<a href=\"http:\/\/vainoithatkhachsan.com\/danh-muc\/man-cua\/\" target=\"_self\" class=\"button primary is-link\"  >\n    <span>Curtain<\/span>\n  <\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2020118787 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n#section_2020118787 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_2020118787 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >HIGHLIGHT PROJECT<\/span><b><\/b><\/h3><\/div>\n\t<section class=\"section slider-noi-bat\" id=\"section_2027883270\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 row-small slider row-slider slider-nav-simple slider-nav-outside slider-nav-light slider-nav-push\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : 5000}'>\n\n  \t\n\t     <div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/tam-trang-tri-03\/\" aria-label=\"T\u1ea5m Trang Tr\u00ed 03\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/tamtrangtri03-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/tamtrangtri03-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/tamtrangtri03-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/tamtrangtri03-280x280.jpg 280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6553\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tDECORATION SHEET\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/tam-trang-tri-03\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">T\u1ea5m Trang Tr\u00ed 03<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/chan-ga-goi-khach-san-gvgg-04\/\" aria-label=\"Ch\u0103n ga g\u1ed1i kh\u00e1ch s\u1ea1n GVGG-04\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/ch\u0103n-ga-goi-05-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/ch\u0103n-ga-goi-05-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/ch\u0103n-ga-goi-05-280x280.jpg 280w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/ch\u0103n-ga-goi-05-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6506\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tCHAIRMAN\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/chan-ga-goi-khach-san-gvgg-04\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Ch\u0103n ga g\u1ed1i kh\u00e1ch s\u1ea1n GVGG-04<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/nem-lo-xo-tui-01\/\" aria-label=\"N\u1ec7m L\u00f2 Xo T\u00fai 01\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/nemloxotui1-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/nemloxotui1-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/nemloxotui1-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/nemloxotui1-280x280.jpg 280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6482\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tBAG HANDLING BAG\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/nem-lo-xo-tui-01\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">N\u1ec7m L\u00f2 Xo T\u00fai 01<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/khan-an-01\/\" aria-label=\"Kh\u0103n \u0102n 01\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/khanan01-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/khanan01-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/khanan01-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/khanan01-280x280.jpg 280w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/khanan01.jpg 350w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6600\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tNAPKIN\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/khan-an-01\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Kh\u0103n \u0102n 01<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/ao-ghe-nha-hang-01\/\" aria-label=\"\u00c1o gh\u1ebf nh\u00e0 h\u00e0ng GVAG-01\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/aoghe03-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/aoghe03-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/aoghe03-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/aoghe03.jpg 600w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/aoghe03-280x280.jpg 280w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/aoghe03-400x400.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6596\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tCHAIR CHAIR\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/ao-ghe-nha-hang-01\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">\u00c1o gh\u1ebf nh\u00e0 h\u00e0ng GVAG-01<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/ruot-goi-01\/\" aria-label=\"Ru\u1ed9t G\u1ed1i 01\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/ruot-goi-1-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/ruot-goi-1-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/ruot-goi-1-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/ruot-goi-1-280x280.jpg 280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6229\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tGUT PILLOW\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/ruot-goi-01\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Ru\u1ed9t G\u1ed1i 01<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-03\/\" aria-label=\"B\u1ea3o v\u1ec7 n\u1ec7m 03\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-300x300.jpeg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-300x300.jpeg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-100x100.jpeg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-280x280.jpeg 280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6233\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tHOTEL OFFERS THE HOTEL\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-03\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">B\u1ea3o v\u1ec7 n\u1ec7m 03<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/nem-lo-xo-01\/\" aria-label=\"N\u1ec7m L\u00f2 Xo 01\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/demloxo-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/demloxo-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/demloxo-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/demloxo-280x280.jpg 280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6472\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tCLEANER\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/nem-lo-xo-01\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">N\u1ec7m L\u00f2 Xo 01<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/khan-mat-01\/\" aria-label=\"Kh\u0103n m\u1eb7t 01\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/336133892-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/336133892-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/336133892-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/336133892-280x280.jpg 280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6225\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tFace Towel\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/khan-mat-01\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Kh\u0103n m\u1eb7t 01<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/ao-choang-tam-01\/\" aria-label=\"\u00c1o cho\u00e0ng t\u1eafm 01\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/monacorobe-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/monacorobe-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/monacorobe-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/monacorobe-600x600.jpg 600w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/monacorobe-280x280.jpg 280w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/monacorobe-400x400.jpg 400w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/monacorobe-768x768.jpg 768w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/monacorobe-800x800.jpg 800w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/monacorobe.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6227\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tBATHROBE\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/ao-choang-tam-01\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">\u00c1o cho\u00e0ng t\u1eafm 01<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/chan-ga-goi-04\/\" aria-label=\"Ch\u0103n ga g\u1ed1i kh\u00e1ch s\u1ea1n GVGG-03\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/ccc2-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/ccc2-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/ccc2-280x280.jpg 280w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/ccc2-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6497\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tCHAIRMAN\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/chan-ga-goi-04\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Ch\u0103n ga g\u1ed1i kh\u00e1ch s\u1ea1n GVGG-03<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/vay-giuong-01\/\" aria-label=\"V\u00e1y Gi\u01b0\u1eddng 01\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/v\u00e1y-gi\u01b0\u1eddng-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/v\u00e1y-gi\u01b0\u1eddng-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/v\u00e1y-gi\u01b0\u1eddng-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/v\u00e1y-gi\u01b0\u1eddng-280x280.jpg 280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6570\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tBATHROOM\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/vay-giuong-01\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">V\u00e1y Gi\u01b0\u1eddng 01<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2027883270 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(42, 190, 233);\n}\n#section_2027883270 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_2027883270 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1324658186\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Blanket<\/span><b><\/b><\/h3><\/div>\n\n  \n    <div class=\"row large-columns-3 medium-columns- small-columns-2 row-small\">\n  \t\n\t     <div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/ruot-goi-01-2\/\" aria-label=\"Ru\u1ed9t g\u1ed1i 01\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08-280x280.jpg 280w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08.jpg 310w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6538\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tGUT PILLOW\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/ruot-goi-01-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Ru\u1ed9t g\u1ed1i 01<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-03\/\" aria-label=\"B\u1ea3o v\u1ec7 n\u1ec7m 03\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-300x300.jpeg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-300x300.jpeg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-100x100.jpeg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-280x280.jpeg 280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6233\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tHOTEL OFFERS THE HOTEL\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-03\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">B\u1ea3o v\u1ec7 n\u1ec7m 03<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-02\/\" aria-label=\"B\u1ea3o v\u1ec7 n\u1ec7m 02\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-600x600.jpg 600w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-280x280.jpg 280w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-400x400.jpg 400w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1.jpg 750w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6235\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tHOTEL OFFERS THE HOTEL\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-02\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">B\u1ea3o v\u1ec7 n\u1ec7m 02<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-01\/\" aria-label=\"B\u1ea3o v\u1ec7 n\u1ec7m 01\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-600x600.jpg 600w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-280x280.jpg 280w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-400x400.jpg 400w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-768x768.jpg 768w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-800x800.jpg 800w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6237\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tHOTEL OFFERS THE HOTEL\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-01\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">B\u1ea3o v\u1ec7 n\u1ec7m 01<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1324658186 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n#section_1324658186 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1324658186 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_18765494\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Pillow<\/span><b><\/b><\/h3><\/div>\n\n  \n    <div class=\"row large-columns-3 medium-columns- small-columns-2 row-small\">\n  \t\n\t     <div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/ruot-goi-01-2\/\" aria-label=\"Ru\u1ed9t g\u1ed1i 01\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08-280x280.jpg 280w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08.jpg 310w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6538\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tGUT PILLOW\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/ruot-goi-01-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Ru\u1ed9t g\u1ed1i 01<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-03\/\" aria-label=\"B\u1ea3o v\u1ec7 n\u1ec7m 03\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-300x300.jpeg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-300x300.jpeg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-100x100.jpeg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-280x280.jpeg 280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6233\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tHOTEL OFFERS THE HOTEL\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-03\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">B\u1ea3o v\u1ec7 n\u1ec7m 03<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-02\/\" aria-label=\"B\u1ea3o v\u1ec7 n\u1ec7m 02\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-600x600.jpg 600w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-280x280.jpg 280w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-400x400.jpg 400w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1.jpg 750w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6235\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tHOTEL OFFERS THE HOTEL\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-02\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">B\u1ea3o v\u1ec7 n\u1ec7m 02<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-01\/\" aria-label=\"B\u1ea3o v\u1ec7 n\u1ec7m 01\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-600x600.jpg 600w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-280x280.jpg 280w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-400x400.jpg 400w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-768x768.jpg 768w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-800x800.jpg 800w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6237\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tHOTEL OFFERS THE HOTEL\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-01\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">B\u1ea3o v\u1ec7 n\u1ec7m 01<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_18765494 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n#section_18765494 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_18765494 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1905031306\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Mattress<\/span><b><\/b><\/h3><\/div>\n\n  \n    <div class=\"row large-columns-3 medium-columns- small-columns-2 row-small\">\n  \t\n\t     <div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/ruot-goi-01-2\/\" aria-label=\"Ru\u1ed9t g\u1ed1i 01\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08-280x280.jpg 280w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08.jpg 310w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6538\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tGUT PILLOW\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/ruot-goi-01-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Ru\u1ed9t g\u1ed1i 01<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-03\/\" aria-label=\"B\u1ea3o v\u1ec7 n\u1ec7m 03\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-300x300.jpeg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-300x300.jpeg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-100x100.jpeg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-280x280.jpeg 280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6233\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tHOTEL OFFERS THE HOTEL\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-03\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">B\u1ea3o v\u1ec7 n\u1ec7m 03<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-02\/\" aria-label=\"B\u1ea3o v\u1ec7 n\u1ec7m 02\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-600x600.jpg 600w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-280x280.jpg 280w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-400x400.jpg 400w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1.jpg 750w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6235\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tHOTEL OFFERS THE HOTEL\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-02\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">B\u1ea3o v\u1ec7 n\u1ec7m 02<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-01\/\" aria-label=\"B\u1ea3o v\u1ec7 n\u1ec7m 01\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-600x600.jpg 600w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-280x280.jpg 280w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-400x400.jpg 400w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-768x768.jpg 768w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-800x800.jpg 800w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6237\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tHOTEL OFFERS THE HOTEL\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-01\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">B\u1ea3o v\u1ec7 n\u1ec7m 01<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1905031306 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n#section_1905031306 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1905031306 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1442596528\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Curtain<\/span><b><\/b><\/h3><\/div>\n\n  \n    <div class=\"row large-columns-3 medium-columns- small-columns-2 row-small\">\n  \t\n\t     <div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/ruot-goi-01-2\/\" aria-label=\"Ru\u1ed9t g\u1ed1i 01\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08-280x280.jpg 280w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/06\/chan-ga-goi-08.jpg 310w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6538\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tGUT PILLOW\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/ruot-goi-01-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Ru\u1ed9t g\u1ed1i 01<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-03\/\" aria-label=\"B\u1ea3o v\u1ec7 n\u1ec7m 03\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-300x300.jpeg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-300x300.jpeg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-100x100.jpeg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN3-280x280.jpeg 280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6233\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tHOTEL OFFERS THE HOTEL\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-03\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">B\u1ea3o v\u1ec7 n\u1ec7m 03<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-02\/\" aria-label=\"B\u1ea3o v\u1ec7 n\u1ec7m 02\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-600x600.jpg 600w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-280x280.jpg 280w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1-400x400.jpg 400w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN1.jpg 750w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6235\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tHOTEL OFFERS THE HOTEL\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-02\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">B\u1ea3o v\u1ec7 n\u1ec7m 02<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" data-animate=\"fadeInUp\">\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-01\/\" aria-label=\"B\u1ea3o v\u1ec7 n\u1ec7m 01\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-300x300.jpg 300w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-100x100.jpg 100w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-600x600.jpg 600w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-280x280.jpg 280w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-400x400.jpg 400w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-768x768.jpg 768w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN-800x800.jpg 800w, https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/BVN.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t  <a class=\"quick-view\" data-prod=\"6237\" href=\"#quick-view\">Quick View<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-7\">\n\t\t\tHOTEL OFFERS THE HOTEL\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/vainoithatkhachsan.com\/en\/products\/bao-ve-nem-01\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">B\u1ea3o v\u1ec7 n\u1ec7m 01<\/a><\/p><\/div><div class=\"price-wrapper\">\n<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1442596528 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n#section_1442596528 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1442596528 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1104624466\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-2079053459\">\n\n\t<div id=\"col-792560971\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >News<\/span><b><\/b><\/h3><\/div>\n\n  \n    <div class=\"row large-columns-2 medium-columns- small-columns-1 row-small slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : false}'>\n\n  <div class=\"col post-item\" data-animate=\"fadeInUp\">\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/bi-kip-chon-noi-cho-phong-khach-chat-hep\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"389\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/1164438051-3.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.32)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">B\u00ed k\u00edp ch\u1ecdn n\u1ed9i th\u1ea5t cho ph\u00f2ng kh\u00e1ch ch\u1eadt h\u1eb9p<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">N\u00f3i \u0111\u1ebfn sofa, b\u1ea1n s\u1ebd ngh\u0129 ngay \u0111\u1ebfn nh\u1eefng ki\u1ec3u sofa c\u00f3 v\u1ebb h\u01a1i\u2026b\u1ec1 th\u1ebf. Vi\u1ec7c k\u00ea sofa ch\u1eafc ch\u1eafn [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">24<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">May<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" data-animate=\"fadeInUp\">\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/vainoithatkhachsan.com\/en\/10-cach-phoi-mau-cho-can-phong-dep\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"570\" height=\"370\" src=\"https:\/\/vainoithatkhachsan.com\/wp-content\/uploads\/2017\/05\/anh-tin-tuc-1-.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.32)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center is-small\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">10 c\u00e1ch ph\u1ed1i m\u00e0u cho c\u0103n ph\u00f2ng \u0111\u1eb9p<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\u0110\u1ed1i v\u1edbi gia \u0111\u00ecnh Vi\u1ec7t, ph\u00f2ng b\u1ebfp lu\u00f4n l\u00e0 n\u01a1i quan tr\u1ecdng v\u00ec \u1edf \u0111\u00f3, gia \u0111\u00ecnh qu\u00e2y qu\u1ea7n sum [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">24<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">May<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-69101260\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" >Videos<\/span><b><\/b><\/h3><\/div>\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><p><iframe loading=\"lazy\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/AoPiLg8DZ3A?feature=oembed\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1104624466 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n#section_1104624466 .ux-shape-divider--top svg {\n  height: 150px;\n  --divider-top-width: 100%;\n}\n#section_1104624466 .ux-shape-divider--bottom svg {\n  height: 150px;\n  --divider-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"page-blank.php","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Home - N\u1ed8I TH\u1ea4T GIA VI\u1ec6T<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vainoithatkhachsan.com\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - N\u1ed8I TH\u1ea4T GIA VI\u1ec6T\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vainoithatkhachsan.com\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"N\u1ed8I TH\u1ea4T GIA VI\u1ec6T\" \/>\n<meta property=\"article:modified_time\" content=\"2017-06-22T04:38:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vainoithatkhachsan.com\/en\/\",\"url\":\"https:\/\/vainoithatkhachsan.com\/en\/\",\"name\":\"Home - N\u1ed8I TH\u1ea4T GIA VI\u1ec6T\",\"isPartOf\":{\"@id\":\"https:\/\/vainoithatkhachsan.com\/en\/#website\"},\"datePublished\":\"2017-05-23T02:36:09+00:00\",\"dateModified\":\"2017-06-22T04:38:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/vainoithatkhachsan.com\/en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vainoithatkhachsan.com\/en\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vainoithatkhachsan.com\/en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Trang ch\u1ee7\",\"item\":\"https:\/\/vainoithatkhachsan.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vainoithatkhachsan.com\/en\/#website\",\"url\":\"https:\/\/vainoithatkhachsan.com\/en\/\",\"name\":\"N\u1ed8I TH\u1ea4T GIA VI\u1ec6T\",\"description\":\"CHUY\u00caN CH\u0102N GA G\u1ed0I N\u1ec6M\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vainoithatkhachsan.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - N\u1ed8I TH\u1ea4T GIA VI\u1ec6T","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vainoithatkhachsan.com\/en\/","og_locale":"en_US","og_type":"article","og_title":"Home - N\u1ed8I TH\u1ea4T GIA VI\u1ec6T","og_url":"https:\/\/vainoithatkhachsan.com\/en\/","og_site_name":"N\u1ed8I TH\u1ea4T GIA VI\u1ec6T","article_modified_time":"2017-06-22T04:38:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vainoithatkhachsan.com\/en\/","url":"https:\/\/vainoithatkhachsan.com\/en\/","name":"Home - N\u1ed8I TH\u1ea4T GIA VI\u1ec6T","isPartOf":{"@id":"https:\/\/vainoithatkhachsan.com\/en\/#website"},"datePublished":"2017-05-23T02:36:09+00:00","dateModified":"2017-06-22T04:38:33+00:00","breadcrumb":{"@id":"https:\/\/vainoithatkhachsan.com\/en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vainoithatkhachsan.com\/en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vainoithatkhachsan.com\/en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Trang ch\u1ee7","item":"https:\/\/vainoithatkhachsan.com\/en\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/vainoithatkhachsan.com\/en\/#website","url":"https:\/\/vainoithatkhachsan.com\/en\/","name":"N\u1ed8I TH\u1ea4T GIA VI\u1ec6T","description":"CHUY\u00caN CH\u0102N GA G\u1ed0I N\u1ec6M","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vainoithatkhachsan.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/vainoithatkhachsan.com\/en\/wp-json\/wp\/v2\/pages\/6140"}],"collection":[{"href":"https:\/\/vainoithatkhachsan.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vainoithatkhachsan.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vainoithatkhachsan.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vainoithatkhachsan.com\/en\/wp-json\/wp\/v2\/comments?post=6140"}],"version-history":[{"count":0,"href":"https:\/\/vainoithatkhachsan.com\/en\/wp-json\/wp\/v2\/pages\/6140\/revisions"}],"wp:attachment":[{"href":"https:\/\/vainoithatkhachsan.com\/en\/wp-json\/wp\/v2\/media?parent=6140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}